{"id":120716,"date":"2022-03-17T13:10:11","date_gmt":"2022-03-17T17:10:11","guid":{"rendered":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109.jpg"},"modified":"2022-03-17T13:10:30","modified_gmt":"2022-03-17T17:10:30","slug":"ncaa-tournament_60459_109","status":"inherit","type":"attachment","link":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2022\/03\/17\/decibel-delight\/ncaa-tournament_60459_109\/","title":{"rendered":"Decibel delight"},"author":43,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-120716","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"217\" height=\"300\" src=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-217x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":900,"height":1244,"file":"2022\/03\/NCAA-tournament_60459_109.jpg","sizes":{"medium":{"file":"NCAA-tournament_60459_109-217x300.jpg","width":217,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-217x300.jpg"},"large":{"file":"NCAA-tournament_60459_109-506x700.jpg","width":506,"height":700,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-506x700.jpg"},"thumbnail":{"file":"NCAA-tournament_60459_109-135x90.jpg","width":135,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-135x90.jpg"},"medium_large":{"file":"NCAA-tournament_60459_109-768x1062.jpg","width":768,"height":1062,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-768x1062.jpg"},"cat_post_thumb_sizewsuposts-3":{"file":"NCAA-tournament_60459_109-99x66.jpg","width":99,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-99x66.jpg"},"cat_post_thumb_sizewsuposts-5":{"file":"NCAA-tournament_60459_109-100x75.jpg","width":100,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-100x75.jpg"},"wrightedu-thumb":{"file":"NCAA-tournament_60459_109-65x90.jpg","width":65,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-65x90.jpg"},"hp-coverstory-img":{"file":"NCAA-tournament_60459_109-500x333.jpg","width":500,"height":333,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109-500x333.jpg"},"full":{"file":"NCAA-tournament_60459_109.jpg","width":900,"height":1244,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109.jpg"}},"image_meta":{"aperture":"0","credit":"Erin Pence","camera":"","caption":"","created_timestamp":"0","copyright":"\u00a9 Wright State University","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":120692,"source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/03\/NCAA-tournament_60459_109.jpg","_links":{"self":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media\/120716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/comments?post=120716"}]}}