{"id":127839,"date":"2022-08-08T10:25:21","date_gmt":"2022-08-08T14:25:21","guid":{"rendered":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1.jpg"},"modified":"2022-08-08T10:26:46","modified_gmt":"2022-08-08T14:26:46","slug":"dkaylah-whitley-headshot__1","status":"inherit","type":"attachment","link":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2022\/08\/08\/dear-dkaylah-unique-whitley\/dkaylah-whitley-headshot__1\/","title":{"rendered":"Dear D\u2019Kaylah Unique Whitley"},"author":43,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-127839","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"173\" src=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-260x173.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Wright State musical theatre major D\u2019Kaylah Unique Whitley has spent the summer on Broadway as an understudy in \u201cDear Evan Hansen.\u201d <a href=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2022\/08\/08\/dear-dkaylah-unique-whitley\/dkaylah-whitley-headshot__1\/\" class=\"morelink\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":800,"file":"2022\/08\/DKaylah-Whitley-Headshot__1.jpg","sizes":{"medium":{"file":"DKaylah-Whitley-Headshot__1-260x173.jpg","width":260,"height":173,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-260x173.jpg"},"large":{"file":"DKaylah-Whitley-Headshot__1-508x339.jpg","width":508,"height":339,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-508x339.jpg"},"thumbnail":{"file":"DKaylah-Whitley-Headshot__1-135x90.jpg","width":135,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-135x90.jpg"},"medium_large":{"file":"DKaylah-Whitley-Headshot__1-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-768x512.jpg"},"cat_post_thumb_sizewsuposts-3":{"file":"DKaylah-Whitley-Headshot__1-99x66.jpg","width":99,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-99x66.jpg"},"cat_post_thumb_sizewsuposts-5":{"file":"DKaylah-Whitley-Headshot__1-100x75.jpg","width":100,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-100x75.jpg"},"wrightedu-thumb":{"file":"DKaylah-Whitley-Headshot__1-80x53.jpg","width":80,"height":53,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-80x53.jpg"},"hp-coverstory-img":{"file":"DKaylah-Whitley-Headshot__1-500x333.jpg","width":500,"height":333,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1-500x333.jpg"},"full":{"file":"DKaylah-Whitley-Headshot__1.jpg","width":1200,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1506280843","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":["Dkaylah","Headshots","sandy springs"]}},"post":127827,"source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2022\/08\/DKaylah-Whitley-Headshot__1.jpg","_links":{"self":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media\/127839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/comments?post=127839"}]}}