{"id":142620,"date":"2023-10-10T10:35:35","date_gmt":"2023-10-10T14:35:35","guid":{"rendered":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2.jpg"},"modified":"2023-10-10T10:35:35","modified_gmt":"2023-10-10T14:35:35","slug":"juliet-and-jocelyn-2","status":"inherit","type":"attachment","link":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2023\/10\/10\/wright-state-womens-center-to-celebrate-30th-anniversary\/juliet-and-jocelyn-2\/","title":{"rendered":"Juliet and Jocelyn&#8211;2"},"author":43,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-142620","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"204\" src=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-260x204.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":550,"file":"2023\/10\/Juliet-and-Jocelyn-2.jpg","filesize":148108,"sizes":{"medium":{"file":"Juliet-and-Jocelyn-2-260x204.jpg","width":260,"height":204,"filesize":12438,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-260x204.jpg"},"large":{"file":"Juliet-and-Jocelyn-2-508x399.jpg","width":508,"height":399,"filesize":34208,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-508x399.jpg"},"thumbnail":{"file":"Juliet-and-Jocelyn-2-135x90.jpg","width":135,"height":90,"filesize":4366,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-135x90.jpg"},"cat_post_thumb_sizewsuposts-3":{"file":"Juliet-and-Jocelyn-2-99x66.jpg","width":99,"height":66,"filesize":3134,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-99x66.jpg"},"cat_post_thumb_sizewsuposts-5":{"file":"Juliet-and-Jocelyn-2-100x75.jpg","width":100,"height":75,"filesize":3396,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-100x75.jpg"},"wrightedu-thumb":{"file":"Juliet-and-Jocelyn-2-80x63.jpg","width":80,"height":63,"filesize":2683,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-80x63.jpg"},"hp-coverstory-img":{"file":"Juliet-and-Jocelyn-2-500x333.jpg","width":500,"height":333,"filesize":31894,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2-500x333.jpg"},"full":{"file":"Juliet-and-Jocelyn-2.jpg","width":700,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":142523,"source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2023\/10\/Juliet-and-Jocelyn-2.jpg","_links":{"self":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media\/142620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/comments?post=142620"}]}}