{"id":52051,"date":"2018-04-30T11:14:49","date_gmt":"2018-04-30T15:14:49","guid":{"rendered":"http:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676.jpg"},"modified":"2018-04-30T11:23:54","modified_gmt":"2018-04-30T15:23:54","slug":"20135_676","status":"inherit","type":"attachment","link":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2018\/04\/30\/spring-2018-commencement-ceremony-in-photos\/20135_676\/","title":{"rendered":"Spring 2018 commencement ceremony in photos"},"author":43,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-52051","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"107\" src=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-260x107.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2000,"height":821,"file":"2018\/04\/20135_676.jpg","sizes":{"thumbnail":{"file":"20135_676-135x90.jpg","width":135,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-135x90.jpg"},"medium":{"file":"20135_676-260x107.jpg","width":260,"height":107,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-260x107.jpg"},"medium_large":{"file":"20135_676-768x315.jpg","width":768,"height":315,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-768x315.jpg"},"large":{"file":"20135_676-508x209.jpg","width":508,"height":209,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-508x209.jpg"},"cat_post_thumb_sizewsuposts-3":{"file":"20135_676-99x66.jpg","width":99,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-99x66.jpg"},"cat_post_thumb_sizewsuposts-5":{"file":"20135_676-100x75.jpg","width":100,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-100x75.jpg"},"wrightedu-thumb":{"file":"20135_676-80x33.jpg","width":80,"height":33,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-80x33.jpg"},"hp-coverstory-img":{"file":"20135_676-500x333.jpg","width":500,"height":333,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676-500x333.jpg"},"full":{"file":"20135_676.jpg","width":2000,"height":821,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"\u00a9 2018 Wright State University","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":52036,"source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/04\/20135_676.jpg","_links":{"self":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media\/52051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/comments?post=52051"}]}}