{"id":52678,"date":"2018-06-04T11:10:34","date_gmt":"2018-06-04T15:10:34","guid":{"rendered":"http:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber.jpg"},"modified":"2018-06-04T11:11:49","modified_gmt":"2018-06-04T15:11:49","slug":"img_2791-jpg","status":"inherit","type":"attachment","link":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2018\/06\/04\/global-reach-2\/img_2791-jpg\/","title":{"rendered":"Global reach"},"author":43,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-52678","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"260\" src=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-260x260.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Kathleen Read Reuber <a href=\"https:\/\/webapp2.wright.edu\/web1\/newsroom\/2018\/06\/04\/global-reach-2\/img_2791-jpg\/\" class=\"morelink\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":300,"height":300,"file":"2018\/06\/Kathleen-Reuber.jpg","sizes":{"thumbnail":{"file":"Kathleen-Reuber-135x90.jpg","width":135,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-135x90.jpg"},"medium":{"file":"Kathleen-Reuber-260x260.jpg","width":260,"height":260,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-260x260.jpg"},"cat_post_thumb_sizewsuposts-3":{"file":"Kathleen-Reuber-99x66.jpg","width":99,"height":66,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-99x66.jpg"},"cat_post_thumb_sizewsuposts-5":{"file":"Kathleen-Reuber-100x75.jpg","width":100,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-100x75.jpg"},"wrightedu-thumb":{"file":"Kathleen-Reuber-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber-80x80.jpg"},"full":{"file":"Kathleen-Reuber.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"IMG_2791.JPG","orientation":"1","keywords":[]}},"post":52671,"source_url":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/files\/2018\/06\/Kathleen-Reuber.jpg","_links":{"self":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media\/52678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/webapp2.wright.edu\/web1\/newsroom\/wp-json\/wp\/v2\/comments?post=52678"}]}}